{"id":9894,"date":"2025-11-18T21:44:04","date_gmt":"2025-11-18T20:44:04","guid":{"rendered":"https:\/\/jobwinner.ai\/?page_id=9894"},"modified":"2025-11-27T18:04:56","modified_gmt":"2025-11-27T17:04:56","slug":"organizzazioni-che-si-occupano-di-politica-sulla-privacy","status":"publish","type":"page","link":"https:\/\/jobwinner.ai\/it\/organizzazioni-che-si-occupano-di-politica-sulla-privacy\/","title":{"rendered":"[Segemento B2B] Privacy Policy"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"9894\" class=\"elementor elementor-9894\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-472a5240 e-flex e-con-boxed e-con e-parent\" data-id=\"472a5240\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-a8c444e elementor-widget elementor-widget-heading\" data-id=\"a8c444e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">politica sulla riservatezza<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-920eb32 elementor-widget elementor-widget-text-editor\" data-id=\"920eb32\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<div>\u00a0<\/div><div><div>\u00a0<\/div><\/div>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-bf9fb6b e-flex e-con-boxed e-con e-parent\" data-id=\"bf9fb6b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-3455f80 elementor-widget elementor-widget-text-editor\" data-id=\"3455f80\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t\t\t\t\t\t<p><b>Ultimo aggiornamento: 4 novembre 2025\u00a0<\/b><\/p><p><span style=\"font-weight: 400;\">Lo scopo della presente Informativa sulla privacy \u00e8 informarti sulle misure che abbiamo adottato per garantire la riservatezza e la protezione dei tuoi dati personali. Illustra come trattiamo e gestiamo i dati personali, perch\u00e9 li raccogliamo e come ne garantiamo la sicurezza.<\/span><\/p><p><span style=\"font-weight: 400;\">La presente Informativa sulla privacy \u00e8 stata<\/span><b> <\/b><span style=\"font-weight: 400;\">redatto in conformit\u00e0 con i principi del Regolamento Generale sulla Protezione dei Dati (&quot;GDPR&quot;). Se, dopo aver letto questo documento, hai ancora domande, puoi contattarci all&#039;indirizzo support@jobwinner.ai e saremo lieti di aiutarti.<\/span><\/p><p><span style=\"font-weight: 400;\">Utilizzando la nostra piattaforma, acconsenti alla raccolta, all&#039;uso e alla condivisione dei tuoi dati personali come descritto nella presente Informativa.\u00a0<\/span><\/p><p>JobWinner \u00e8 gestito da\u00a0<span style=\"font-weight: bold;\">JobWinner Ventures Limited<\/span>, Titolare del trattamento di tutti i dati personali trattati tramite il Servizio.<br \/>Sede legale: Unit 2, 2 Bridge Street, Athlone, Westmeath, N37 F1W4, Irlanda<br \/>Per domande relative alla privacy, contattare:\u00a0<span style=\"font-weight: bold;\">support@jobwinner.ai<\/span><\/p><h1><b>Panoramica generale<\/b><\/h1><p data-start=\"116\" data-end=\"241\"><strong data-start=\"116\" data-end=\"241\">JobWinner \u00e8 una piattaforma di sviluppo della carriera basata sull&#039;intelligenza artificiale utilizzata da due gruppi di utenti: chi cerca lavoro e i membri dell&#039;organizzazione.<\/strong><\/p><ul><li data-start=\"243\" data-end=\"537\">I candidati sono studenti, partecipanti o individui che utilizzano gli strumenti della piattaforma per creare domande di lavoro, migliorare la propria occupabilit\u00e0 e prepararsi ai colloqui.<\/li><li data-start=\"243\" data-end=\"537\">I membri dell&#039;organizzazione sono dipendenti, consulenti o personale dell&#039;organizzazione che supportano gli utenti nel loro sviluppo professionale.<\/li><\/ul><p data-start=\"539\" data-end=\"736\">I candidati interagiscono direttamente con gli strumenti di carriera della piattaforma, mentre i membri dell&#039;organizzazione accedono a una dashboard di consulenza che offre approfondimenti limitati e opzioni amministrative per assistere i candidati.<span style=\"font-size: 1rem;\">\u00a0<\/span><\/p><h4><span style=\"font-weight: bold;\">Ruoli e accesso ai dati<\/span><\/h4><p data-start=\"368\" data-end=\"595\">JobWinner Ventures Limited agisce come <strong data-start=\"407\" data-end=\"431\">\u00a0Titolare del trattamento dei dati<\/strong> per tutti i dati personali trattati tramite la piattaforma JobWinner. JobWinner determina le finalit\u00e0 e le modalit\u00e0 di tutti i trattamenti effettuati nell&#039;ambito del Servizio.<\/p><p data-start=\"837\" data-end=\"1122\">I membri dell&#039;organizzazione agiscono solo come <strong data-start=\"870\" data-end=\"895\">Destinatari autorizzati<\/strong> E <strong data-start=\"900\" data-end=\"924\">Utenti amministrativi<\/strong>, con accesso limitato ad alcune informazioni dei candidati, esclusivamente per supportare l&#039;occupabilit\u00e0. L&#039;accesso \u00e8 di sola visualizzazione all&#039;interno delle funzionalit\u00e0 predefinite della dashboard e non comporta un&#039;elaborazione indipendente.<\/p><p data-start=\"1124\" data-end=\"1288\">JobWinner e l&#039;organizzazione fanno <strong data-start=\"1158\" data-end=\"1190\">non agire come contitolari del trattamento<\/strong>. Ciascuna parte \u00e8 responsabile esclusivamente delle operazioni di trattamento che effettua per le proprie finalit\u00e0.<\/p><h1><b>1. Tipologia di dati raccolti<\/b><\/h1><p><span style=\"font-weight: 400;\">Per offrirti i migliori risultati possibili dal nostro Servizio, potremmo chiederti alcuni dati personali. Potremmo anche elaborare informazioni fornite dall&#039;Organizzazione a cui appartieni. I dati personali che raccogliamo possono includere informazioni che ti identificano direttamente, nonch\u00e9 informazioni che descrivono le tue interazioni con la piattaforma.<\/span><\/p><h2><b>1.1 Dati di identit\u00e0<\/b><\/h2><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Nome, cognome, indirizzo email, password e affiliazione istituzionale (se applicabile).<\/span><\/li><\/ul><h2><b>1.2 Dati del profilo professionale<\/b><\/h2><p><span style=\"font-weight: 400;\">Potremmo raccogliere:<\/span><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Tutti i CV, i riassunti, il profilo Linkedin, le descrizioni di lavoro e qualsiasi altro documento correlato al lavoro che carichi<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Risposte di pratica per l&#039;intervista o testo generato tramite la piattaforma<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Obiettivi o preferenze di carriera<\/span><\/li><\/ul><p><span style=\"font-weight: 400;\">Queste informazioni vengono utilizzate esclusivamente per fornirti gli strumenti e i consigli all&#039;interno del Servizio.<\/span><\/p><h2><b>1.3 Dati di interazione e utilizzo<\/b><\/h2><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><p><span style=\"font-weight: 400;\">Registrazioni relative al modo in cui utilizzi la piattaforma: accessi, orari delle sessioni, funzionalit\u00e0 utilizzate (ad esempio, personalizzazione del CV, preparazione ai colloqui), frequenza di utilizzo e monitoraggio dei progressi.<\/span><\/p><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><p><span style=\"font-weight: 400;\">Registri del percorso dell&#039;utente (ad esempio, come si naviga all&#039;interno dell&#039;app, quali strumenti si utilizzano pi\u00f9 spesso e risultati delle interazioni).<\/span><\/p><\/li><\/ul><h2><b>1.4 Dati tecnici e del dispositivo<\/b><\/h2><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Indirizzo IP, tipo di browser, sistema operativo, identificatori del dispositivo, dati sulla posizione (se abilitati) e cookie.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Registri degli errori, dati sulle prestazioni e timestamp di connessione per aiutarci a mantenere la qualit\u00e0 del servizio.<\/span><\/li><\/ul><h2><b>1.5 Dati forniti da terze parti e organizzazioni<\/b><\/h2><p><span style=\"font-weight: 400;\">La tua organizzazione potrebbe fornire informazioni limitate necessarie per configurare il tuo account o verificare l&#039;idoneit\u00e0 all&#039;accesso, ad esempio:<\/span><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Stato di iscrizione<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Programma, coorte o dipartimento<\/span><\/li><\/ul><div><h2><strong data-start=\"1499\" data-end=\"1544\">1.6 Dati che raccogliamo dai membri dell&#039;organizzazione<\/strong><\/h2><p data-start=\"1546\" data-end=\"2071\">Se accedi a JobWinner per conto della tua Organizzazione (ad esempio, come parte del team di carriera o accademico), elaboreremo i tuoi dati di contatto professionali (come nome e indirizzo email), le credenziali di accesso e i registri delle attivit\u00e0 necessari per fornire il servizio concesso in licenza dell&#039;Organizzazione. Ci\u00f2 include la possibilit\u00e0 di caricare documenti, gestire i profili degli studenti e utilizzare gli strumenti resi disponibili tramite l&#039;account della tua Organizzazione. Questi dati non vengono utilizzati per scopi di marketing e non vengono mai condivisi con terze parti.<\/p><\/div><h1><b>2. Finalit\u00e0 del trattamento dei dati<\/b><\/h1><p><span style=\"font-weight: 400;\">Utilizziamo i tuoi dati personali esclusivamente in conformit\u00e0 con l&#039;articolo 6 del GDPR, in base alle seguenti basi giuridiche: necessit\u00e0 contrattuale, interessi legittimi, obbligo legale e consenso (articolo 6 del GDPR). Le finalit\u00e0 del trattamento dei tuoi dati sono descritte di seguito.\u00a0<\/span><\/p><p><span style=\"font-weight: 400;\">Non utilizziamo le tue informazioni per pubblicizzare o promuovere JobWinner al di fuori dell&#039;account della tua organizzazione e non vendiamo, affittiamo o sfruttiamo commercialmente i tuoi dati.<\/span><\/p><h2><b>2.1 Fornitura del Servizio<\/b><\/h2><p><span style=\"font-weight: 400;\">Utilizziamo i tuoi dati per fornirti i servizi della nostra piattaforma:\u00a0\u00a0<\/span><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Fornire le funzionalit\u00e0 della piattaforma<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Abilita la personalizzazione del CV, la creazione di lettere di presentazione, l&#039;analisi della corrispondenza del lavoro e la preparazione ai colloqui<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Genera feedback e raccomandazioni personalizzati<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Salva e visualizza i tuoi progressi, documenti e attivit\u00e0<\/span><\/li><\/ul><h2><b>2.2 Personalizzazione<\/b><\/h2><p><span style=\"font-weight: 400;\">Per aiutarti a ottenere risultati pi\u00f9 pertinenti, potremmo personalizzare raccomandazioni, suggerimenti di contenuti, feedback basati sulle competenze e miglioramenti relativi alla tua occupabilit\u00e0<\/span><\/p><h2><b>2.3 Comunicazione<\/b><\/h2><p><span style=\"font-weight: 400;\">Potremmo utilizzare le tue informazioni per inviarti notifiche sul tuo account, rispondere alle domande dell&#039;assistenza clienti e fornire aggiornamenti relativi al Servizio o alla tua Organizzazione<\/span><\/p><p><span style=\"font-weight: 400;\">Noi lo facciamo <\/span><b>non<\/b><span style=\"font-weight: 400;\"> inviare e-mail di marketing esterne.<\/span><\/p><h2><b>2.4 Supporto per i membri dell&#039;organizzazione<\/b><\/h2><p><span style=\"font-weight: 400;\">Per supportare l&#039;orientamento professionale, <\/span><b>Membri dell&#039;organizzazione<\/b><span style=\"font-weight: 400;\"> pu\u00f2 accedere a informazioni limitate su <\/span><b>Cercatori di lavoro<\/b><span style=\"font-weight: 400;\"> A:<\/span><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Monitorare e valutare il modo in cui gli studenti o i partecipanti interagiscono con la piattaforma.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Generare report sull&#039;utilizzo complessivo e sui risultati.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Fornire orientamento professionale, formazione e risorse aggiuntive.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Inviarti informazioni rilevanti sui servizi dell&#039;istituto, comprese opportunit\u00e0 di formazione ed eventi.<\/span><\/li><\/ul><h2><b>2.5 Miglioramento della piattaforma<\/b><\/h2><p><span style=\"font-weight: 400;\">I modelli di utilizzo aggregati e anonimizzati ci aiutano a migliorare le prestazioni della piattaforma, a sviluppare nuove funzionalit\u00e0 e a correggere problemi tecnici<\/span><\/p><h2><b>2.6 Obblighi legali e di sicurezza<\/b><\/h2><p><span style=\"font-weight: 400;\">Potremmo elaborare i dati per garantire la sicurezza dei dati, prevenire frodi o abusi e rispettare i requisiti normativi<\/span><\/p><h1><b>3. Destinatari dei dati<\/b><\/h1><p><span style=\"font-weight: 400;\">L&#039;accesso ai dati personali raccolti \u00e8 consentito solo in base alla rigorosa necessit\u00e0 di conoscerli.<\/span><\/p><h2><b>3.1 Dipendenti e subappaltatori di JobWinner<\/b><\/h2><p><span style=\"font-weight: 400;\">Il personale autorizzato accede ai dati esclusivamente per:<\/span><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Manutenzione della piattaforma<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Supporto tecnico<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Sicurezza e stabilit\u00e0 del sistema<\/span><\/li><\/ul><p><span style=\"font-weight: 400;\">Tutti i dipendenti di JobWinner sono vincolati da accordi di riservatezza. I fornitori di servizi utilizzati da JobWinner elaborano i dati <strong data-start=\"889\" data-end=\"904\">esclusivamente<\/strong> per conto di JobWinner e in conformit\u00e0 con gli accordi conformi al GDPR.<\/span><\/p><h2><b>3.2 Membri dell&#039;organizzazione<\/b><\/h2><p><span style=\"font-size: 1rem;\">Membri dell&#039;organizzazione\u00a0<b>agire come<\/b><\/span><span style=\"font-size: 1rem;\">\u00a0<\/span><strong style=\"font-size: 1rem;\" data-start=\"1127\" data-end=\"1152\">Destinatari autorizzati<\/strong><span style=\"font-size: 1rem;\"> E <\/span><strong style=\"font-size: 1rem;\" data-start=\"1157\" data-end=\"1181\">Utenti amministrativi<\/strong><span style=\"font-size: 1rem;\">, e potrebbe ricevere un accesso limitato e di sola visualizzazione a determinate informazioni del richiedente lavoro al solo scopo di supportare l&#039;occupabilit\u00e0.<\/span><\/p><p><span style=\"font-weight: 400;\">Ci\u00f2 pu\u00f2 includere:<\/span><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Strumenti utilizzati dal richiedente lavoro<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Aziende e lavori per cui sono state create le candidature<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Punteggi del profilo LinkedIn e aree di miglioramento<\/span><\/li><\/ul><p><span style=\"font-weight: 400;\">Questi dati vengono condivisi esclusivamente per migliorare i risultati del candidato e devono essere trattati dall&#039;Organizzazione sotto la propria responsabilit\u00e0 legale.<\/span><\/p><h2><b>3.3 Fornitori di servizi<\/b><\/h2><p data-start=\"469\" data-end=\"743\"><span style=\"font-size: 1rem;\">I Fornitori di Servizi possono avere accesso ai tuoi dati personali solo per svolgere queste attivit\u00e0 per nostro conto. Sono contrattualmente obbligati a non utilizzare o divulgare i tuoi dati per altri scopi e devono rispettare le leggi applicabili in materia di protezione dei dati.<\/span><\/p><p data-start=\"987\" data-end=\"1025\">I nostri attuali fornitori di servizi includono:<\/p><p data-start=\"1027\" data-end=\"1731\"><span style=\"font-size: 1rem;\">\u25cf Digital Ocean \u2013 Per i servizi di hosting<\/span><\/p><p data-start=\"1027\" data-end=\"1731\"><span style=\"font-size: 1rem;\">\u25cf\u00a0<\/span>Google \u2013 Per analisi (Google Analytics, Google Tag Manager), autenticazione (Google Sign-In) e analisi dell&#039;utilizzo.<br data-start=\"1219\" data-end=\"1222\" \/>\u25cf Firebase \u2013 Per l&#039;autenticazione, la gestione del database, l&#039;hosting e l&#039;infrastruttura del codice (fornito da Google).<br data-start=\"1330\" data-end=\"1333\" \/>\u25cf Brevo (in precedenza Sendinblue) \u2013 Per l&#039;hosting di posta elettronica e l&#039;invio di comunicazioni.<br data-start=\"1477\" data-end=\"1480\" \/>\u25cf Cookiebot (di Usercentrics) \u2013 Per la gestione del consenso sui cookie.<br data-start=\"1542\" data-end=\"1545\" \/>\u25cf OpenAI \u2013 Per generare output personalizzati (ad esempio CV, lettere di presentazione) basati sulle informazioni fornite dall&#039;utente.<\/p><p data-start=\"1733\" data-end=\"2004\">Garantiamo che tutti i Fornitori di Servizi gestiscano i tuoi dati in modo responsabile e in conformit\u00e0 con le normative sulla privacy come il GDPR e il CCPA. Per maggiori dettagli su come questi fornitori trattano i tuoi dati, consulta le loro informative sulla privacy utilizzando i link forniti sopra.<\/p><h2><b>3.4 Transazioni societarie<\/b><\/h2><p><span style=\"font-weight: 400;\">Se JobWinner dovesse subire una fusione, un&#039;acquisizione o un evento aziendale simile, i dati potrebbero essere condivisi con affiliati o investitori in base a requisiti di protezione dei dati legalmente vincolanti.<\/span><\/p><h2><b>3.5 Autorit\u00e0 legali<\/b><\/h2><p><span style=\"font-weight: 400;\">Potremmo divulgare dati personali laddove richiesto dalla legge, da una citazione in giudizio o da una legittima richiesta governativa.<\/span><\/p><h1><b>4. Trasferimenti al di fuori dell&#039;Unione Europea<\/b><\/h1><p><span style=\"font-weight: 400;\">La piattaforma \u00e8 ospitata ad Amsterdam, Paesi Bassi (UE). Qualora i dati vengano trasferiti al di fuori dell&#039;UE, vengono applicate adeguate garanzie, quali:<\/span><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Decisioni di adeguatezza della Commissione europea<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Clausole contrattuali standard (SCC)<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Ulteriori misure tecniche e organizzative<\/span><\/li><\/ul><p><span style=\"font-weight: 400;\">In questo modo i tuoi dati rimangono protetti indipendentemente dalla loro posizione.<\/span><\/p><h1><b>5. Conservazione dei dati<\/b><\/h1><p><span style=\"font-weight: 400;\">Conserviamo i dati personali solo per il tempo necessario a fornire il Servizio.<\/span><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">I dati personali vengono conservati per un massimo di <\/span><b>due anni dopo il tuo ultimo accesso<\/b><span style=\"font-weight: 400;\">.<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Puoi eliminare il tuo account in qualsiasi momento utilizzando l&#039;opzione &quot;Elimina il mio account&quot; nel tuo profilo.<\/span><\/li><\/ul><p><span style=\"font-weight: 400;\">Dopo l&#039;eliminazione dell&#039;account, i dati vengono cancellati in modo sicuro o resi anonimi entro un periodo di tempo ragionevole, salvo quanto richiesto dalla legge.<\/span><\/p><h1><b style=\"font-family: -apple-system, BlinkMacSystemFont, 'Segoe UI', Roboto, 'Helvetica Neue', Arial, 'Noto Sans', sans-serif, 'Apple Color Emoji', 'Segoe UI Emoji', 'Segoe UI Symbol', 'Noto Color Emoji';\">6. Sicurezza e privacy<\/b><\/h1><p><span style=\"font-weight: 400;\">Implementiamo solide misure tecniche e organizzative per proteggere le tue informazioni. Queste includono:<\/span><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Crittografia efficace (a riposo e in transito)<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Controllo rigoroso degli accessi con autenticazione<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Audit regolari e valutazioni di sicurezza<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Politiche interne complete sulla privacy<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Accordi di non divulgazione obbligatori per tutto il personale JobWinner<\/span><\/li><\/ul><p><span style=\"font-weight: 400;\">La nostra priorit\u00e0 \u00e8 mantenere la riservatezza, l&#039;integrit\u00e0 e la disponibilit\u00e0 dei tuoi dati in ogni momento.<\/span><\/p><h1><b>7. Termini ed esercizio dei diritti<\/b><\/h1><p><span style=\"font-weight: 400;\">A seconda della giurisdizione in cui risiedi, potresti avere i seguenti diritti in merito ai tuoi dati personali:<\/span><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><p><b>Diritto di accesso:<\/b><span style=\"font-weight: 400;\"> Per ottenere conferma e copia dei tuoi dati personali.<\/span><\/p><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><p><b>Diritto di rettifica:<\/b><span style=\"font-weight: 400;\"> Per correggere dati inesatti o incompleti.<\/span><\/p><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><p><b>Diritto alla cancellazione (\u201cdiritto all\u2019oblio\u201d): <\/b><span style=\"font-weight: 400;\">Per richiedere la cancellazione dei tuoi dati personali, fatte salve le eccezioni previste dalla legge.<\/span><\/p><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><p><b>Diritto di limitazione del trattamento:<\/b><span style=\"font-weight: 400;\"> Per limitare il modo in cui i tuoi dati vengono utilizzati in determinate situazioni.<\/span><\/p><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><p><b>Diritto alla portabilit\u00e0 dei dati:<\/b><span style=\"font-weight: 400;\"> Per ricevere i tuoi dati in un formato strutturato e leggibile da una macchina.<\/span><\/p><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><p><b>Diritto di opposizione: <\/b><span style=\"font-weight: 400;\">Per opporsi a determinati trattamenti, incluso il marketing.<\/span><\/p><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><p><b>Diritto di revoca del consenso: <\/b><span style=\"font-weight: 400;\">Di revocare il consenso in qualsiasi momento, senza pregiudicare la liceit\u00e0 del trattamento precedente.<\/span><\/p><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><p><b>Diritto di presentare un reclamo: <\/b><span style=\"font-weight: 400;\">Se ritieni che i tuoi dati siano stati trattati illecitamente, hai il diritto di presentare un reclamo all&#039;Autorit\u00e0 locale per la protezione dei dati. In Irlanda, l&#039;Autorit\u00e0 di vigilanza \u00e8 l&#039; <\/span><b>Commissione per la protezione dei dati<\/b><span style=\"font-weight: 400;\"> : <\/span><a href=\"http:\/\/www.dataprotection.ie\" target=\"_blank\" rel=\"noopener\"><span style=\"font-weight: 400;\">www.dataprotection.ie<\/span><\/a><\/p><\/li><\/ul><p><span style=\"font-weight: 400;\">Per esercitare questi diritti, contattaci all&#039;indirizzo: support@jobwinner.ai.<\/span><\/p><h1><b>8. Modifiche alla presente Informativa sulla privacy<\/b><\/h1><p><span style=\"font-weight: 400;\">Ci riserviamo il diritto di modificare o aggiornare la presente Informativa sulla privacy in qualsiasi momento.<\/span><span style=\"font-weight: 400;\"><br \/><\/span><span style=\"font-weight: 400;\"> Se dovessero verificarsi modifiche sostanziali, ti informeremo tramite:<\/span><\/p><ul><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Un avviso visibile all&#039;interno della piattaforma, oppure<\/span><\/li><li style=\"font-weight: 400;\" aria-level=\"1\"><span style=\"font-weight: 400;\">Un&#039;e-mail inviata al tuo indirizzo registrato<\/span><\/li><\/ul><p><span style=\"font-weight: 400;\">Se non sei d&#039;accordo con la Politica aggiornata, puoi chiudere il tuo account in qualsiasi momento.<\/span><\/p><h1><b>9. Utilizzo dei cookie<\/b><\/h1><p><span style=\"font-weight: 400;\">Per maggiori informazioni su come i cookie e le tecnologie di tracciamento vengono utilizzati sulla piattaforma, consultare il nostro <\/span><a href=\"https:\/\/jobwinner.ai\/it\/politica-sui-cookie\/\"><b>Informativa sui cookie<\/b><\/a><span style=\"font-weight: 400;\">.<\/span><\/p><p>Per gli utenti che accedono a JobWinner tramite un&#039;Organizzazione, non utilizziamo cookie analitici, di marketing o di preferenza. Vengono impostati solo i cookie strettamente necessari per la sicurezza e le funzionalit\u00e0 di base.<\/p><h1><b>10. Responsabile della protezione dei dati<\/b><\/h1><p><span style=\"font-weight: 400;\">Il nostro responsabile della protezione dei dati e rappresentante UE nominato \u00e8:<\/span><\/p><ul><li><b>Pablo Tirso Tonutti Martinez<\/b><\/li><li>Email di contatto: <a style=\"font-family: -apple-system, BlinkMacSystemFont, 'Segoe UI', Roboto, 'Helvetica Neue', Arial, 'Noto Sans', sans-serif, 'Apple Color Emoji', 'Segoe UI Emoji', 'Segoe UI Symbol', 'Noto Color Emoji';\" href=\"mailto:support@jobwinner.ai\">support@jobwinner.ai<\/a><\/li><li>Indirizzo: Unit\u00e0 2, 2 Bridge Street Athlone, WESTMEATH, N37 F1W4, Irlanda<\/li><\/ul>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Privacy Policy \u00a0\u00a0 Last Updated: November 4th, 2025\u00a0 The purpose of this Privacy Policy is to inform you of the measures we have put in place to ensure the privacy and protection of your personal data. It explains how we process and manage\u00a0 personal data, why we collect it, and how we ensure its security. [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"wf_page_folders":[26],"class_list":["post-9894","page","type-page","status-publish","hentry"],"jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/jobwinner.ai\/it\/wp-json\/wp\/v2\/pages\/9894","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/jobwinner.ai\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/jobwinner.ai\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/jobwinner.ai\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/jobwinner.ai\/it\/wp-json\/wp\/v2\/comments?post=9894"}],"version-history":[{"count":0,"href":"https:\/\/jobwinner.ai\/it\/wp-json\/wp\/v2\/pages\/9894\/revisions"}],"wp:attachment":[{"href":"https:\/\/jobwinner.ai\/it\/wp-json\/wp\/v2\/media?parent=9894"}],"wp:term":[{"taxonomy":"wf_page_folders","embeddable":true,"href":"https:\/\/jobwinner.ai\/it\/wp-json\/wp\/v2\/wf_page_folders?post=9894"}],"curies":[{"name":"parola chiave","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}